{"id":49449,"date":"2025-01-08T10:04:19","date_gmt":"2025-01-08T09:04:19","guid":{"rendered":"https:\/\/www.fenice.care\/business\/riparare-pelli-pigmentate\/"},"modified":"2025-03-31T10:39:19","modified_gmt":"2025-03-31T08:39:19","slug":"repairing-pigmented-leather","status":"publish","type":"page","link":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/","title":{"rendered":"Repairing Pigmented Leather"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jn31oivz-997956ffc08a2033d9255738092b15f7\">\n.avia-section.av-jn31oivz-997956ffc08a2033d9255738092b15f7{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Banner-pigmentata.jpg);\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-jn31oivz-997956ffc08a2033d9255738092b15f7 main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap sidebar_right'  data-section-bg-repeat='stretch' data-av_minimum_height_px='400'><div class='container av-section-cont-open' style='height:400px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c\">\n#top .av-special-heading.av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c{\npadding-bottom:10px;\ncolor:#000000;\n}\nbody .av-special-heading.av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c .special-heading-inner-border{\nborder-color:#000000;\n}\n.av-special-heading.av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-jrq4n7p9-2aa4c1fd396ff62d489c2fff36b2720c av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-1  avia-builder-el-no-sibling  av-linked-heading'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  ><\/p>\n<h2 style=\"text-align: center; letter-spacing: 0px; color: black;\">Repairing Pigmented Leather<\/h2>\n<p><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-jujiv56y-312806b9887a6fd588ba3733b9312759 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  el_before_av_section  av-medium-hide av-small-hide av-mini-hide avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jn322ovo-fe979d4478022cd77c2a4484a7df323a\">\n.flex_column.av-jn322ovo-fe979d4478022cd77c2a4484a7df323a{\nborder-radius:0px 0px 0px 0px;\npadding:0px 120px 0px 120px;\n}\n<\/style>\n<div  class='flex_column av-jn322ovo-fe979d4478022cd77c2a4484a7df323a av_one_full  avia-builder-el-3  avia-builder-el-no-sibling  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-42a17i-fe30654586d90d7692c9be00ed6629ea\">\n#top .av-special-heading.av-42a17i-fe30654586d90d7692c9be00ed6629ea{\npadding-bottom:10px;\ncolor:#000000;\n}\nbody .av-special-heading.av-42a17i-fe30654586d90d7692c9be00ed6629ea .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-42a17i-fe30654586d90d7692c9be00ed6629ea .special-heading-inner-border{\nborder-color:#000000;\n}\n.av-special-heading.av-42a17i-fe30654586d90d7692c9be00ed6629ea .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-42a17i-fe30654586d90d7692c9be00ed6629ea av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-4  el_before_av_hr  avia-builder-el-first  av-linked-heading'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  ><\/p>\n<h2 style=\"text-align: center; letter-spacing: 0px; color: #c5a454;\">Repairing Pigmented Leather<\/h2>\n<p><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi8ttx5-83bd3347d72164477d82439868b0af9e\">\n#top .hr.av-jqi8ttx5-83bd3347d72164477d82439868b0af9e{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-jqi8ttx5-83bd3347d72164477d82439868b0af9e .hr-inner{\nwidth:100px;\nborder-color:#c5a454;\n}\n<\/style>\n<div  class='hr av-jqi8ttx5-83bd3347d72164477d82439868b0af9e hr-custom  avia-builder-el-5  el_after_av_heading  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi8fe8v-e2f96c452b9d0dab9f94f6c71663463e\">\n#top .av_textblock_section.av-jqi8fe8v-e2f96c452b9d0dab9f94f6c71663463e .avia_textblock{\ncolor:#0a0a0a;\n}\n<\/style>\n<section  class='av_textblock_section av-jqi8fe8v-e2f96c452b9d0dab9f94f6c71663463e '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\">Select the type of issue to be solved from the menu to find advice from Fenice experts and products most suited to the task.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\">With all leather-care products, remember to shake the bottle well before use (particularly in the case of pigments and dyes) and test all products on a hidden area before use<\/span><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi9507e-ffe41139ede66bcdbeb0569fadfe125b\">\n#top .hr.hr-invisible.av-jqi9507e-ffe41139ede66bcdbeb0569fadfe125b{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-jqi9507e-ffe41139ede66bcdbeb0569fadfe125b hr-invisible  avia-builder-el-7  el_after_av_textblock  el_before_av_toggle_container '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jofo9pfg-d3b72310d6fee7860f30cabdad425d24\">\n#top .togglecontainer.av-jofo9pfg-d3b72310d6fee7860f30cabdad425d24 p.toggler{\ncolor:#000000;\nborder-color:#c5a454;\n}\n#top .togglecontainer.av-jofo9pfg-d3b72310d6fee7860f30cabdad425d24 p.toggler .toggle_icon{\ncolor:#000000;\nborder-color:#000000;\n}\n#top .togglecontainer.av-jofo9pfg-d3b72310d6fee7860f30cabdad425d24 .toggle_wrap .toggle_content{\ncolor:#000000;\nborder-color:#c5a454;\n}\n<\/style>\n<div  class='togglecontainer av-jofo9pfg-d3b72310d6fee7860f30cabdad425d24 av-minimal-toggle  avia-builder-el-8  el_after_av_hr  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-d7p67y-3fab95902c87880736c10fb5f248b4f4'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"Surface abrasion\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Surface abrasion\" data-aria_expanded=\"Click to collapse: Surface abrasion\">Surface abrasion<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2457 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li>Use our Ultra Rapid Leather Cleaner<\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Glue WB, then let dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the repair isn\u2019t satisfactory, proceed as follows:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2458 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-2-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Apply multiple layers of Surface Repair<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Use Grain Copier on an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Warm the copy of the grain until you see a change in color. Immediately place the copy over the scratch and press down for 10 seconds. Let cool for 20 seconds before removing from the leather.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up to the area and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ax8uni-7095c58109e374d2fd5e85fd0fdf070b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"Hole, cigarettes burns\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Hole, cigarettes burns\" data-aria_expanded=\"Click to collapse: Hole, cigarettes burns\">Hole, cigarettes burns<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2661 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Bruciature-sigaretta.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li>C<span class=\"s2\">lean with Ultra Rapid Leather Cleaner<\/span><\/li>\n<li>Rinse with water and dry<\/li>\n<li class=\"li1\"><span class=\"s2\">Glue the Support Mesh beneath the hole using Leather Glue WB and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Fill most of the hole with a layer of Heat Repair and dry with a professional drier. Apply with a second layer until the hole is completely covered, but do not let dry.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Grain Copier onto an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Place the copy of the grain onto the second layer of Heat Repair. Place the Heat Paper Repair over the copy of the grain. Heat with the iron for 30 seconds in slow, circular motions and applying a slight pressure. Let cool for 1 minute<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine. Test the color on a hidden area<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply the Touch-up with a soft cloth, then dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-91wq4u-ee50a64cacfc50ad03b76d16e76931e0'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-3' data-fake-id='#toggle-id-3' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3' data-slide-speed=\"200\" data-title=\"Deep cracks\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Deep cracks\" data-aria_expanded=\"Click to collapse: Deep cracks\">Deep cracks<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' aria-labelledby='toggle-toggle-id-3' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2695 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Crepe-profonde-1.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F for Leather<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Fill the crack with the Mender and leave to air dry for at least 4 hours<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">When the product is completely dry, sand with 400 Sand Paper<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Remove the powdery residue with a damp cloth<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li>Spray the Basecoat Color onto the entire area to be treated<\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-6t17bi-be9a7819f87f87267f7bea0f26687eff'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-4' data-fake-id='#toggle-id-4' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-4' data-slide-speed=\"200\" data-title=\"Grease - Oil\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Grease - Oil\" data-aria_expanded=\"Click to collapse: Grease - Oil\">Grease - Oil<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-4' aria-labelledby='toggle-toggle-id-4' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2659 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Grasso-Olio.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and the white side of our dual-action sponge. Eliminate any residual dirt with water using the blue side of the dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray our Leather &amp; Textile Degreaser only on the greasy area. Let rest for at least four hours.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Vacuum up the powder, then remove any remaining residue with a dry sponge. If the grease is not completely removed, repeat step 2.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean again with our Leather Cleaner and the blue side of our dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the finish is damaged, execute the following steps:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2475 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Grasso-olio-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated, then dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-dxsv2-e047bb916245a44d1b716c57dc99ff7d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-5' data-fake-id='#toggle-id-5' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-5' data-slide-speed=\"200\" data-title=\"Deep ink spots\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Deep ink spots\" data-aria_expanded=\"Click to collapse: Deep ink spots\">Deep ink spots<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-5' aria-labelledby='toggle-toggle-id-5' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2464 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Inchiostro-penetrato-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Remove the spot using our Ink Remover<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean with Ultra Rapid Leather Cleaner or Deep Cleaner F (as necessary)<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the spot has not been completely removed, proceed as follows:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2664 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Inchiostro-penetrato-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine. Test the color on a hidden area<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply the Touch-up with a soft cloth, then dry<\/span><\/li>\n<li><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-384ff2-96a4f31d6808b1eedd570e911fe5b5db'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-6' data-fake-id='#toggle-id-6' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-6' data-slide-speed=\"200\" data-title=\"Fresh ink spots\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Fresh ink spots\" data-aria_expanded=\"Click to collapse: Fresh ink spots\">Fresh ink spots<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-6' aria-labelledby='toggle-toggle-id-6' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2466 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Inchiostro-recente-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Remove the spot using our Ink Remover<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-3747em-0c6dc2ba34fbe710e038510010f66039'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-7' data-fake-id='#toggle-id-7' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-7' data-slide-speed=\"200\" data-title=\"Mold\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Mold\" data-aria_expanded=\"Click to collapse: Mold\">Mold<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-7' aria-labelledby='toggle-toggle-id-7' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2467 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Muffa-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Mold Remover to a cloth and delicately rub the area to be treated.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Repeat after 24 hours if necessary.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean again using Leather Cleaner to remove any residue of Mold Remover.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector with a cloth and rub lightly in circular motions.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let dry, then lightly buff if desired.<\/span><\/li>\n<\/ol>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em><span class=\"s1\">If the finish is damaged, execute the following steps:<\/span><\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2468 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Muffa-2-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ci5oda-6808217168910ebe2c1bc04bd51f3ebe'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-8' data-fake-id='#toggle-id-8' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-8' data-slide-speed=\"200\" data-title=\"Squeaky leather\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Squeaky leather\" data-aria_expanded=\"Click to collapse: Squeaky leather\">Squeaky leather<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-8' aria-labelledby='toggle-toggle-id-8' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-1735 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg\" alt=\"\" width=\"1000\" height=\"170\" srcset=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg 1000w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-600x102.jpg 600w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-300x51.jpg 300w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-768x131.jpg 768w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-705x120.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Revive<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry and buff with a cloth if desired<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ayacym-57bb6b04f6504df957fbf2f4de6fa679'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-9' data-fake-id='#toggle-id-9' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-9' data-slide-speed=\"200\" data-title=\"Dry, stiff leather\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Dry, stiff leather\" data-aria_expanded=\"Click to collapse: Dry, stiff leather\">Dry, stiff leather<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-9' aria-labelledby='toggle-toggle-id-9' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-1735 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg\" alt=\"\" width=\"1000\" height=\"170\" srcset=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg 1000w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-600x102.jpg 600w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-300x51.jpg 300w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-768x131.jpg 768w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-705x120.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean the leather with our Leather Cleaner and the white side of our dual-action sponge. Eliminate any residual dirt with water using the blue side of the dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Revive<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry and buff with a cloth if desired<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-6ytda-af38d794d42fa9774ad32859abeed248'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-10' data-fake-id='#toggle-id-10' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-10' data-slide-speed=\"200\" data-title=\"Spew\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Spew\" data-aria_expanded=\"Click to collapse: Spew\">Spew<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-10' aria-labelledby='toggle-toggle-id-10' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2469 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Repus-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Spew Remover to a cloth and delicately rub the area to be treated.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Refresh the cloth frequently and always use a clean section of the cloth.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let rest for 24 hours, then repeat the process if necessary.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector with a cloth and rub lightly in circular motions.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let dry, then lightly buff if desired.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-7phr7y-c347cc64ff6586c931e541d6b133002c'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-11' data-fake-id='#toggle-id-11' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-11' data-slide-speed=\"200\" data-title=\"Discoloration\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Discoloration\" data-aria_expanded=\"Click to collapse: Discoloration\">Discoloration<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-11' aria-labelledby='toggle-toggle-id-11' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2470 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Scolorimento-1.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-645a8e-9423a599f239eaba294fa853cdf74573'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-12' data-fake-id='#toggle-id-12' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-12' data-slide-speed=\"200\" data-title=\"Cracking\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Cracking\" data-aria_expanded=\"Click to collapse: Cracking\">Cracking<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-12' aria-labelledby='toggle-toggle-id-12' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2476 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Screpolature.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-4lurku-e0b46594975c6e6c20b1d15ccf84fa86'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-13' data-fake-id='#toggle-id-13' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-13' data-slide-speed=\"200\" data-title=\"Old stains\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Old stains\" data-aria_expanded=\"Click to collapse: Old stains\">Old stains<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-13' aria-labelledby='toggle-toggle-id-13' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2471 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Sporco-sedimentato-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Use our Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2iyne6-ba9acf5aee3e411faf42a5feb9f5a0e2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-14' data-fake-id='#toggle-id-14' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-14' data-slide-speed=\"200\" data-title=\"Scratches\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Scratches\" data-aria_expanded=\"Click to collapse: Scratches\">Scratches<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-14' aria-labelledby='toggle-toggle-id-14' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2472 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Strisci-e-graffi-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Use our Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Glue WB, then let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em><span class=\"s1\">If the repair isn\u2019t satisfactory, proceed as follows:<\/span><\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2667 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Strisci-e-graffi-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Apply multiple layers of Surface Repair<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Use Grain Copier on an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Warm the copy of the grain until you see a change in color. Immediately place the copy over the scratch and press down for 10 seconds. Let cool for 20 seconds before removing from the leather.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up to the area and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-jujiva07-2d494bc374f7e837f01197d581b6efa3 main_color avia-section-default avia-no-border-styling  avia-builder-el-9  el_after_av_section  el_before_av_section  av-desktop-hide avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jn322ovo-22-d7873a986217ce1028bea9f34deae8cc\">\n.flex_column.av-jn322ovo-22-d7873a986217ce1028bea9f34deae8cc{\nborder-radius:0px 0px 0px 0px;\npadding:0px 30px 0px 30px;\n}\n<\/style>\n<div  class='flex_column av-jn322ovo-22-d7873a986217ce1028bea9f34deae8cc av_one_full  avia-builder-el-10  avia-builder-el-no-sibling  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-418qm6-4d8421ce089496e7c5d650e02854d5eb\">\n#top .av-special-heading.av-418qm6-4d8421ce089496e7c5d650e02854d5eb{\npadding-bottom:10px;\ncolor:#000000;\n}\nbody .av-special-heading.av-418qm6-4d8421ce089496e7c5d650e02854d5eb .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-418qm6-4d8421ce089496e7c5d650e02854d5eb .special-heading-inner-border{\nborder-color:#000000;\n}\n.av-special-heading.av-418qm6-4d8421ce089496e7c5d650e02854d5eb .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-418qm6-4d8421ce089496e7c5d650e02854d5eb av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-11  el_before_av_hr  avia-builder-el-first  av-linked-heading'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  ><\/p>\n<h2 style=\"text-align: center; letter-spacing: 0px; color: #c5a454;\">Repairing Pigmented Leather<\/h2>\n<p><\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi8ttx5-21-482eab254216bbbb05f2f6c8eb4afa92\">\n#top .hr.av-jqi8ttx5-21-482eab254216bbbb05f2f6c8eb4afa92{\nmargin-top:20px;\nmargin-bottom:30px;\n}\n.hr.av-jqi8ttx5-21-482eab254216bbbb05f2f6c8eb4afa92 .hr-inner{\nwidth:100px;\nborder-color:#c5a454;\n}\n<\/style>\n<div  class='hr av-jqi8ttx5-21-482eab254216bbbb05f2f6c8eb4afa92 hr-custom  avia-builder-el-12  el_after_av_heading  el_before_av_textblock  hr-center hr-icon-no'><span class='hr-inner inner-border-av-border-thin'><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi8fe8v-20-a466fc60be94d191b48a419f894328a3\">\n#top .av_textblock_section.av-jqi8fe8v-20-a466fc60be94d191b48a419f894328a3 .avia_textblock{\ncolor:#0a0a0a;\n}\n<\/style>\n<section  class='av_textblock_section av-jqi8fe8v-20-a466fc60be94d191b48a419f894328a3 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\">Select the type of issue to be solved from the menu to find advice from Fenice experts and products most suited to the task.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: center;\"><span class=\"s1\">With all leather-care products, remember to shake the bottle well before use (particularly in the case of pigments and dyes) and test all products on a hidden area before use<\/span><\/p>\n<\/div><\/section><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqi9507e-19-48fee0bf8ab0c844f8a01f5097662517\">\n#top .hr.hr-invisible.av-jqi9507e-19-48fee0bf8ab0c844f8a01f5097662517{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-jqi9507e-19-48fee0bf8ab0c844f8a01f5097662517 hr-invisible  avia-builder-el-14  el_after_av_textblock  el_before_av_toggle_container '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jofo9pfg-18-3714e5103c9a399dffd35c1dda6ff03a\">\n#top .togglecontainer.av-jofo9pfg-18-3714e5103c9a399dffd35c1dda6ff03a p.toggler{\ncolor:#000000;\nborder-color:#c5a454;\n}\n#top .togglecontainer.av-jofo9pfg-18-3714e5103c9a399dffd35c1dda6ff03a p.toggler .toggle_icon{\ncolor:#000000;\nborder-color:#000000;\n}\n#top .togglecontainer.av-jofo9pfg-18-3714e5103c9a399dffd35c1dda6ff03a .toggle_wrap .toggle_content{\ncolor:#000000;\nborder-color:#c5a454;\n}\n<\/style>\n<div  class='togglecontainer av-jofo9pfg-18-3714e5103c9a399dffd35c1dda6ff03a av-minimal-toggle  avia-builder-el-15  el_after_av_hr  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-d7p67y-17-6bb2997b83bc952bd9248e8d49ff0503'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-15' data-fake-id='#toggle-id-15' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-15' data-slide-speed=\"200\" data-title=\"Surface abrasion\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Surface abrasion\" data-aria_expanded=\"Click to collapse: Surface abrasion\">Surface abrasion<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-15' aria-labelledby='toggle-toggle-id-15' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2457 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li>Use our Ultra Rapid Leather Cleaner<\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Glue WB, then let dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the repair isn\u2019t satisfactory, proceed as follows:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2458 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-2-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Apply multiple layers of Surface Repair<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Use Grain Copier on an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Warm the copy of the grain until you see a change in color. Immediately place the copy over the scratch and press down for 10 seconds. Let cool for 20 seconds before removing from the leather.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up to the area and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ax8uni-16-3577e878e1617bfa987a73619d72cc14'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-16' data-fake-id='#toggle-id-16' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-16' data-slide-speed=\"200\" data-title=\"Hole, cigarettes burns\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Hole, cigarettes burns\" data-aria_expanded=\"Click to collapse: Hole, cigarettes burns\">Hole, cigarettes burns<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-16' aria-labelledby='toggle-toggle-id-16' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2661 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Bruciature-sigaretta.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li>C<span class=\"s2\">lean with Ultra Rapid Leather Cleaner<\/span><\/li>\n<li>Rinse with water and dry<\/li>\n<li class=\"li1\"><span class=\"s2\">Glue the Support Mesh beneath the hole using Leather Glue WB and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Fill most of the hole with a layer of Heat Repair and dry with a professional drier. Apply with a second layer until the hole is completely covered, but do not let dry.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Grain Copier onto an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Place the copy of the grain onto the second layer of Heat Repair. Place the Heat Paper Repair over the copy of the grain. Heat with the iron for 30 seconds in slow, circular motions and applying a slight pressure. Let cool for 1 minute<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine. Test the color on a hidden area<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply the Touch-up with a soft cloth, then dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-91wq4u-15-bf020ecfcf0867b838a35a3c37898442'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-17' data-fake-id='#toggle-id-17' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-17' data-slide-speed=\"200\" data-title=\"Deep cracks\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Deep cracks\" data-aria_expanded=\"Click to collapse: Deep cracks\">Deep cracks<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-17' aria-labelledby='toggle-toggle-id-17' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2695 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Crepe-profonde-1.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F for Leather<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Fill the crack with the Mender and leave to air dry for at least 4 hours<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">When the product is completely dry, sand with 400 Sand Paper<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Remove the powdery residue with a damp cloth<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li>Spray the Basecoat Color onto the entire area to be treated<\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-6t17bi-14-ece71a3d9d074832625aaa1b4d1c2a4c'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-18' data-fake-id='#toggle-id-18' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-18' data-slide-speed=\"200\" data-title=\"Grease - Oil\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Grease - Oil\" data-aria_expanded=\"Click to collapse: Grease - Oil\">Grease - Oil<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-18' aria-labelledby='toggle-toggle-id-18' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-2659 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Grasso-Olio.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and the white side of our dual-action sponge. Eliminate any residual dirt with water using the blue side of the dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray our Leather &amp; Textile Degreaser only on the greasy area. Let rest for at least four hours.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Vacuum up the powder, then remove any remaining residue with a dry sponge. If the grease is not completely removed, repeat step 2.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean again with our Leather Cleaner and the blue side of our dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the finish is damaged, execute the following steps:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2475 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Grasso-olio-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated, then dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-dxsv2-13-648562ecc51e051f29e4d028de461d99'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-19' data-fake-id='#toggle-id-19' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-19' data-slide-speed=\"200\" data-title=\"Deep ink spots\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Deep ink spots\" data-aria_expanded=\"Click to collapse: Deep ink spots\">Deep ink spots<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-19' aria-labelledby='toggle-toggle-id-19' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2464 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Inchiostro-penetrato-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Remove the spot using our Ink Remover<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean with Ultra Rapid Leather Cleaner or Deep Cleaner F (as necessary)<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em>If the spot has not been completely removed, proceed as follows:<\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2664 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Inchiostro-penetrato-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine. Test the color on a hidden area<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply the Touch-up with a soft cloth, then dry<\/span><\/li>\n<li><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-384ff2-12-04671de505016a6969ac3d7baad1df17'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-20' data-fake-id='#toggle-id-20' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-20' data-slide-speed=\"200\" data-title=\"Fresh ink spots\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Fresh ink spots\" data-aria_expanded=\"Click to collapse: Fresh ink spots\">Fresh ink spots<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-20' aria-labelledby='toggle-toggle-id-20' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2466 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Inchiostro-recente-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Remove the spot using our Ink Remover<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-3747em-11-c7e2acd28a9926228b13fb58023ddfa3'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-21' data-fake-id='#toggle-id-21' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-21' data-slide-speed=\"200\" data-title=\"Mold\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Mold\" data-aria_expanded=\"Click to collapse: Mold\">Mold<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-21' aria-labelledby='toggle-toggle-id-21' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2467 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Muffa-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Mold Remover to a cloth and delicately rub the area to be treated.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Repeat after 24 hours if necessary.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean again using Leather Cleaner to remove any residue of Mold Remover.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector with a cloth and rub lightly in circular motions.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let dry, then lightly buff if desired.<\/span><\/li>\n<\/ol>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em><span class=\"s1\">If the finish is damaged, execute the following steps:<\/span><\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"wp-image-2468 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Muffa-2-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ci5oda-10-d32acecc12784532ee7e4e3420cedac2'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-22' data-fake-id='#toggle-id-22' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-22' data-slide-speed=\"200\" data-title=\"Squeaky leather\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Squeaky leather\" data-aria_expanded=\"Click to collapse: Squeaky leather\">Squeaky leather<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-22' aria-labelledby='toggle-toggle-id-22' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-1735 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg\" alt=\"\" width=\"1000\" height=\"170\" srcset=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg 1000w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-600x102.jpg 600w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-300x51.jpg 300w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-768x131.jpg 768w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-705x120.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Revive<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry and buff with a cloth if desired<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ayacym-9-ce7d6de8b16afea22191785909ee9eb9'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-23' data-fake-id='#toggle-id-23' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-23' data-slide-speed=\"200\" data-title=\"Dry, stiff leather\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Dry, stiff leather\" data-aria_expanded=\"Click to collapse: Dry, stiff leather\">Dry, stiff leather<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-23' aria-labelledby='toggle-toggle-id-23' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"size-full wp-image-1735 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg\" alt=\"\" width=\"1000\" height=\"170\" srcset=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca.jpg 1000w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-600x102.jpg 600w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-300x51.jpg 300w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-768x131.jpg 768w, https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/01\/Pelle-secca-705x120.jpg 705w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean the leather with our Leather Cleaner and the white side of our dual-action sponge. Eliminate any residual dirt with water using the blue side of the dual-action sponge.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Revive<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let air dry and buff with a cloth if desired<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2bsl9q-b5bd79203041992f3959938955d40c44'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-24' data-fake-id='#toggle-id-24' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-24' data-slide-speed=\"200\" data-title=\"Spew\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Spew\" data-aria_expanded=\"Click to collapse: Spew\">Spew<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-24' aria-labelledby='toggle-toggle-id-24' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2469 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Repus-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Spew Remover to a cloth and delicately rub the area to be treated.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Refresh the cloth frequently and always use a clean section of the cloth.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let rest for 24 hours, then repeat the process if necessary.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector with a cloth and rub lightly in circular motions.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Let dry, then lightly buff if desired.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-7phr7y-8-e90d7d682bdd2cbf0482683f92459bff'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-25' data-fake-id='#toggle-id-25' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-25' data-slide-speed=\"200\" data-title=\"Discoloration\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Discoloration\" data-aria_expanded=\"Click to collapse: Discoloration\">Discoloration<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-25' aria-labelledby='toggle-toggle-id-25' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2470 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Scolorimento-1.jpg\" alt=\"\" width=\"1000\" height=\"227\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with our Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Clean deeply with Deep Cleaner F<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray a thin layer of Extra Adhesion onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray the Basecoat Color onto the entire area to be treated<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Spray Top Coat Gloss or Matte, depending on the amount of shine desired. To get the right texture and aroma, add either the Slip or Non-Slip feel modifier (FM), Eco-crosslinker, and the Leather Fragrance.<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-645a8e-7-eae281aef8f444bd5515e1ccec5738a7'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-26' data-fake-id='#toggle-id-26' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-26' data-slide-speed=\"200\" data-title=\"Cracking\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Cracking\" data-aria_expanded=\"Click to collapse: Cracking\">Cracking<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-26' aria-labelledby='toggle-toggle-id-26' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2476 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Screpolature.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Clean with Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-4lurku-6-567f4d17c8e981ca0012ecb24d9f781b'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-27' data-fake-id='#toggle-id-27' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-27' data-slide-speed=\"200\" data-title=\"Old stains\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Old stains\" data-aria_expanded=\"Click to collapse: Old stains\">Old stains<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-27' aria-labelledby='toggle-toggle-id-27' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2471 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Sporco-sedimentato-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Use our Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-3 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2iyne6-5-f1d2d3cd6a1fe3634eafc0ecb16f1ced'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-28' data-fake-id='#toggle-id-28' class='toggler  av-title-above av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-28' data-slide-speed=\"200\" data-title=\"Scratches\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Scratches\" data-aria_expanded=\"Click to collapse: Scratches\">Scratches<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-28' aria-labelledby='toggle-toggle-id-28' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color av-inherit-font-color hasCustomColor av-inherit-border-color'  itemprop=\"text\" ><p><img decoding=\"async\" class=\"wp-image-2472 size-full aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Strisci-e-graffi-1-1.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Use our Ultra Rapid Leather Cleaner<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Rinse with water and dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Glue WB, then let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p class=\"p1\" style=\"text-align: center;\"><span style=\"color: #ff0000;\"><em><span class=\"s1\">If the repair isn\u2019t satisfactory, proceed as follows:<\/span><\/em><\/span><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-2667 aligncenter\" src=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/03\/Strisci-e-graffi-2.jpg\" alt=\"\" width=\"1000\" height=\"170\" \/><\/p>\n<ol>\n<li class=\"li1\"><span class=\"s2\">Apply multiple layers of Surface Repair<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Use Grain Copier on an area where the grain of the leather is well defined to copy it. Leave to dry for a few minutes.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Warm the copy of the grain until you see a change in color. Immediately place the copy over the scratch and press down for 10 seconds. Let cool for 20 seconds before removing from the leather.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Mix the colors and adjust the percentages as necessary in order to achieve the desired color. Add Dulling Agent at a ratio of no more than 1:1 to get the right degree of shine.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Touch-up to the area and let dry<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Apply Leather Protector and dry<\/span><\/li>\n<\/ol>\n<p style=\"text-align: center;\"><strong><div class=\"woocommerce columns-4 \"><\/div><\/strong><\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jn2yxd6k-f6af781b160d5c6121045b3404b4c032\">\n.avia-section.av-jn2yxd6k-f6af781b160d5c6121045b3404b4c032{\nbackground-color:#f7f7f7;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_4'  class='avia-section av-jn2yxd6k-f6af781b160d5c6121045b3404b4c032 main_color avia-section-default avia-no-border-styling  avia-builder-el-16  el_after_av_section  el_before_av_section  av-medium-hide av-small-hide av-mini-hide avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-5x3rn-1142c9ea70043917ee03d789c13b5b37\">\n.flex_column.av-5x3rn-1142c9ea70043917ee03d789c13b5b37{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-5x3rn-1142c9ea70043917ee03d789c13b5b37 av_one_fourth  avia-builder-el-17  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-56203-0dddfb84d9d5e1559bf2ff2ff7ee92c8\">\n.flex_column.av-56203-0dddfb84d9d5e1559bf2ff2ff7ee92c8{\nborder-radius:0px 0px 0px 0px;\npadding:30px 30px 30px 30px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-56203-0dddfb84d9d5e1559bf2ff2ff7ee92c8 av_one_half  avia-builder-el-18  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3s93dq-1f3ea0420e4e71f1e05943931da5391f\">\n#top .av-special-heading.av-3s93dq-1f3ea0420e4e71f1e05943931da5391f{\npadding-bottom:10px;\ncolor:#c5a454;\n}\nbody .av-special-heading.av-3s93dq-1f3ea0420e4e71f1e05943931da5391f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-3s93dq-1f3ea0420e4e71f1e05943931da5391f .special-heading-inner-border{\nborder-color:#c5a454;\n}\n.av-special-heading.av-3s93dq-1f3ea0420e4e71f1e05943931da5391f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-3s93dq-1f3ea0420e4e71f1e05943931da5391f av-special-heading-h2 custom-color-heading  avia-builder-el-19  el_before_av_textblock  avia-builder-el-first  av-linked-heading'><h2 class='av-special-heading-tag '  itemprop=\"headline\"  ><\/p>\n<h2 style=\"text-align: center; letter-spacing: 0px; color: #c5a354;\">Contact us<\/h2>\n<p><\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-jn2z6dqz-80b54c2032b8d058354d9be4ff7fd6da '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\">For whatever you may need, simply send an email to\u00a0<a href=\"mailto:info@fenice.care\">info@fenice.care<\/a><br \/>\nor use the form below<\/p>\n<\/div><\/section><br \/>\n<\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-12hqf-e8ffb8b657dfccf118141ae7ca61b9f7\">\n.flex_column.av-12hqf-e8ffb8b657dfccf118141ae7ca61b9f7{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-12hqf-e8ffb8b657dfccf118141ae7ca61b9f7 av_one_fourth  avia-builder-el-22  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jn2yxd6k-4-62d49948cbd06b3453f0125a99cbeb76\">\n.avia-section.av-jn2yxd6k-4-62d49948cbd06b3453f0125a99cbeb76{\nbackground-color:#f7f7f7;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_5'  class='avia-section av-jn2yxd6k-4-62d49948cbd06b3453f0125a99cbeb76 main_color avia-section-default avia-no-border-styling  avia-builder-el-23  el_after_av_section  avia-builder-el-last  av-desktop-hide avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-56203-3-7c6d7d3968d7c927b485ed791ec6c712\">\n.flex_column.av-56203-3-7c6d7d3968d7c927b485ed791ec6c712{\nborder-radius:0px 0px 0px 0px;\npadding:30px 30px 30px 30px;\nbackground-color:#ffffff;\n}\n<\/style>\n<div  class='flex_column av-56203-3-7c6d7d3968d7c927b485ed791ec6c712 av_one_full  avia-builder-el-24  avia-builder-el-no-sibling  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2pypgu-773387b2235ca87806733262c36f9584\">\n#top .av-special-heading.av-2pypgu-773387b2235ca87806733262c36f9584{\npadding-bottom:10px;\ncolor:#c5a454;\n}\nbody .av-special-heading.av-2pypgu-773387b2235ca87806733262c36f9584 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2pypgu-773387b2235ca87806733262c36f9584 .special-heading-inner-border{\nborder-color:#c5a454;\n}\n.av-special-heading.av-2pypgu-773387b2235ca87806733262c36f9584 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2pypgu-773387b2235ca87806733262c36f9584 av-special-heading-h2 custom-color-heading  avia-builder-el-25  el_before_av_textblock  avia-builder-el-first  av-linked-heading'><h2 class='av-special-heading-tag '  itemprop=\"headline\"  ><\/p>\n<h2 style=\"text-align: center; letter-spacing: 0px; color: #c5a354;\">Contact us<\/h2>\n<p><\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-jn2z6dqz-2-3f6df6f9b772362fdf9fb917dca115d8 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p style=\"text-align: center;\">For whatever you may need, simply send an email to\u00a0<a href=\"mailto:info@fenice.care\">info@fenice.care<\/a><br \/>\nor use the form below<\/p>\n<\/div><\/section><br \/>\n<\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_5'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-49449'><div class='entry-content-wrapper clearfix'><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":49299,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"footnotes":""},"class_list":["post-49449","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Repairing Pigmented Leather - Fenice care system<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Repairing Pigmented Leather - Fenice care system\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/\" \/>\n<meta property=\"og:site_name\" content=\"Fenice care system\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fenicecs\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T08:39:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/04\/Grafico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"39 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/\",\"url\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/\",\"name\":\"Repairing Pigmented Leather - Fenice care system\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fenice.care\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Abrasioni-superficiali-1-1.jpg\",\"datePublished\":\"2025-01-08T09:04:19+00:00\",\"dateModified\":\"2025-03-31T08:39:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fenice.care\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Abrasioni-superficiali-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fenice.care\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Abrasioni-superficiali-1-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/repairing-pigmented-leather\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/home-nuova\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business\",\"item\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/business\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Repairing Pigmented Leather\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/\",\"name\":\"Fenice care system\",\"description\":\"I professionisti della pelle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#organization\",\"name\":\"Fenice Care System SpA Unip.\",\"url\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fenice.care\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo-fenice-padding.png\",\"contentUrl\":\"https:\\\/\\\/www.fenice.care\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo-fenice-padding.png\",\"width\":442,\"height\":284,\"caption\":\"Fenice Care System SpA Unip.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fenice.care\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fenicecs\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fenice_care_system_official\\\/?hl=it\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/fenicecaresystem-spa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Repairing Pigmented Leather - Fenice care system","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/","og_locale":"en_US","og_type":"article","og_title":"Repairing Pigmented Leather - Fenice care system","og_url":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/","og_site_name":"Fenice care system","article_publisher":"https:\/\/www.facebook.com\/fenicecs\/","article_modified_time":"2025-03-31T08:39:19+00:00","og_image":[{"width":1300,"height":813,"url":"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/04\/Grafico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"39 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/","url":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/","name":"Repairing Pigmented Leather - Fenice care system","isPartOf":{"@id":"https:\/\/www.fenice.care\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/#primaryimage"},"image":{"@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-1-1.jpg","datePublished":"2025-01-08T09:04:19+00:00","dateModified":"2025-03-31T08:39:19+00:00","breadcrumb":{"@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/#primaryimage","url":"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-1-1.jpg","contentUrl":"https:\/\/www.fenice.care\/wp-content\/uploads\/2019\/02\/Abrasioni-superficiali-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fenice.care\/en\/business\/repairing-pigmented-leather\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fenice.care\/en\/home-nuova\/"},{"@type":"ListItem","position":2,"name":"Business","item":"https:\/\/www.fenice.care\/en\/business\/"},{"@type":"ListItem","position":3,"name":"Repairing Pigmented Leather"}]},{"@type":"WebSite","@id":"https:\/\/www.fenice.care\/en\/#website","url":"https:\/\/www.fenice.care\/en\/","name":"Fenice care system","description":"I professionisti della pelle","publisher":{"@id":"https:\/\/www.fenice.care\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fenice.care\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.fenice.care\/en\/#organization","name":"Fenice Care System SpA Unip.","url":"https:\/\/www.fenice.care\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.fenice.care\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.fenice.care\/wp-content\/uploads\/2018\/10\/logo-fenice-padding.png","contentUrl":"https:\/\/www.fenice.care\/wp-content\/uploads\/2018\/10\/logo-fenice-padding.png","width":442,"height":284,"caption":"Fenice Care System SpA Unip."},"image":{"@id":"https:\/\/www.fenice.care\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fenicecs\/","https:\/\/www.instagram.com\/fenice_care_system_official\/?hl=it","https:\/\/it.linkedin.com\/company\/fenicecaresystem-spa"]}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/pages\/49449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/comments?post=49449"}],"version-history":[{"count":1,"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/pages\/49449\/revisions"}],"predecessor-version":[{"id":49450,"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/pages\/49449\/revisions\/49450"}],"up":[{"embeddable":true,"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/pages\/49299"}],"wp:attachment":[{"href":"https:\/\/www.fenice.care\/en\/wp-json\/wp\/v2\/media?parent=49449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}